{"id":30682,"date":"2015-12-09T17:07:50","date_gmt":"2015-12-09T17:07:50","guid":{"rendered":"https:\/\/www.jesuspeiro.com\/wp-jesuspeiro\/de\/nota-legal\/"},"modified":"2025-04-18T14:14:11","modified_gmt":"2025-04-18T14:14:11","slug":"nota-legal","status":"publish","type":"page","link":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">0. OBJETO Y ACEPTACI\u00d3N<\/h2>\n\n\n\n<p>El presente aviso legal regula el uso y utilizaci\u00f3n del sitio web www.jesuspeiro.com (en adelante, LA WEB), del que es titular INTERSPOSA SA (en adelante, JESUS PEIRO).<\/p>\n\n\n\n<p>La navegaci\u00f3n por el sitio web de JESUS PEIRO le atribuye la condici\u00f3n de usuario del mismo y conlleva su aceptaci\u00f3n plena y sin reservas de todas y cada una de las condiciones publicadas en este aviso legal, advirtiendo de que dichas condiciones podr\u00e1n ser modificadas sin notificaci\u00f3n previa por parte de JESUS PEIRO, en cuyo caso se proceder\u00e1 a su publicaci\u00f3n y aviso con la m\u00e1xima antelaci\u00f3n posible.<\/p>\n\n\n\n<p>Por ello es recomendable leer atentamente su contenido en caso de desear acceder y hacer uso de la informaci\u00f3n y de los servicios ofrecidos desde este sitio web.<\/p>\n\n\n\n<p>El usuario adem\u00e1s, se obliga a hacer un uso correcto del sitio web de conformidad con las leyes, la buena fe, el orden p\u00fablico, los usos del tr\u00e1fico y el presente Aviso Legal, y responder\u00e1 frente a JESUS PEIRO o frente a terceros, de cualesquiera da\u00f1os y perjuicios que pudieran causarse como consecuencia del incumplimiento de dicha obligaci\u00f3n.<\/p>\n\n\n\n<p>Cualquier utilizaci\u00f3n distinta a la autorizada est\u00e1 expresamente prohibida, pudiendo JESUS PEIRO denegar o retirar el acceso y su uso en cualquier momento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. IDENTIFICACI\u00d3N Y COMUNICACIONES<\/h2>\n\n\n\n<p>JESUS PEIRO, en cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, le informa de que:<br>\u2022 Su denominaci\u00f3n social es: INTERSPOSA SA<br>\u2022 Su nombre comercial es: JESUS PEIRO<br>\u2022 Su CIF es: A58567439<br>\u2022 Su domicilio social est\u00e1 en: C\/ Noi del Sucre, 61 &#8211; 08840 Viladecans -Barcelona<br>\u2022 Inscrita en el Registro Mercantil de [Datos de inscripci\u00f3n en el registro<br>mercantil, en su caso]<\/p>\n\n\n\n<p>Para comunicarse con nosotros, ponemos a su disposici\u00f3n diferentes medios de contacto que detallamos a continuaci\u00f3n:<\/p>\n\n\n\n<p>Tel\u00e9fono: 936473002<br>Email: info@jesuspeiro.com<\/p>\n\n\n\n<p>Todas las notificaciones y comunicaciones entre los usuarios y JESUS PEIRO se considerar\u00e1n eficaces, a todos los efectos, cuando se realicen a trav\u00e9s de cualquier medio de los detallados anteriormente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. CONDICIONES DE ACCESO Y UTILIZACI\u00d3N<\/h2>\n\n\n\n<p>El sitio web y sus servicios son de acceso libre y gratuito. No obstante, JESUS<br>PEIRO puede condicionar la utilizaci\u00f3n de algunos de los servicios ofrecidos en su web a la previa cumplimentaci\u00f3n del correspondiente formulario.<\/p>\n\n\n\n<p>El usuario garantiza la autenticidad y actualidad de todos aquellos datos que comunique a JESUS PEIRO y ser\u00e1 el \u00fanico responsable de las manifestaciones falsas o inexactas que realice.<\/p>\n\n\n\n<p>El usuario se compromete expresamente a hacer un uso adecuado de los<br>contenidos y servicios de JESUS PEIRO y a no emplearlos para, entre otros:<\/p>\n\n\n\n<p>a) Difundir contenidos delictivos, violentos, pornogr\u00e1ficos, racistas, xen\u00f3fobos, ofensivos, de apolog\u00eda del terrorismo o, en general, contrarios a la ley o al orden p\u00fablico.<br>b) Introducir en la red virus inform\u00e1ticos o realizar actuaciones susceptibles de alterar, estropear, interrumpir o generar errores o da\u00f1os en los documentos electr\u00f3nicos, datos o sistemas f\u00edsicos y l\u00f3gicos de JESUS PEIRO o de terceras personas; as\u00ed como obstaculizar el acceso de otros usuarios al sitio web y a sus servicios mediante el consumo masivo de los recursos inform\u00e1ticos a trav\u00e9s de los cuales JESUS PEIRO presta sus servicios.<br>c) Intentar acceder a las cuentas de correo electr\u00f3nico de otros usuarios o a<br>\u00e1reas restringidas de los sistemas inform\u00e1ticos de JESUS PEIRO o de<br>terceros y, en su caso, extraer informaci\u00f3n.<br>d) Vulnerar los derechos de propiedad intelectual o industrial, as\u00ed como violar la confidencialidad de la informaci\u00f3n de JESUS PEIRO o de terceros.<br>e) Suplantar la identidad de cualquier otro usuario.<br>f) Reproducir, copiar, distribuir, poner a disposici\u00f3n de, o cualquier otra forma de comunicaci\u00f3n p\u00fablica, transformar o modificar los contenidos, a menos que se cuente con la autorizaci\u00f3n del titular de los correspondientes<br>derechos o ello resulte legalmente permitido.<br>g) Recabar datos con finalidad publicitaria y de remitir publicidad de cualquier clase y comunicaciones con fines de venta u otras de naturaleza comercial sin que medie su previa solicitud o consentimiento.<\/p>\n\n\n\n<p>Todos los contenidos del sitio web, como textos, fotograf\u00edas, gr\u00e1ficos, im\u00e1genes, iconos, tecnolog\u00eda, software, as\u00ed como su dise\u00f1o gr\u00e1fico y c\u00f3digos fuente, constituyen una obra cuya propiedad pertenece a JESUS PEIRO, sin que puedan entenderse cedidos al usuario ninguno de los derechos de explotaci\u00f3n sobre los mismos m\u00e1s all\u00e1 de lo estrictamente necesario para el correcto uso de la web.<\/p>\n\n\n\n<p>En definitiva, los usuarios que accedan a este sitio web pueden visualizar los contenidos y efectuar, en su caso, copias privadas autorizadas siempre que los elementos reproducidos no sean cedidos posteriormente a terceros, ni se instalen a servidores conectados a redes, ni sean objeto de ning\u00fan tipo de explotaci\u00f3n.<\/p>\n\n\n\n<p>Asimismo, todas las marcas, nombres comerciales o signos distintivos de cualquier clase que aparecen en el sitio web son propiedad de JESUS PEIRO, sin que pueda entenderse que el uso o acceso al mismo atribuya al usuario derecho alguno sobre los mismos.<\/p>\n\n\n\n<p>La distribuci\u00f3n, modificaci\u00f3n, cesi\u00f3n o comunicaci\u00f3n p\u00fablica de los contenidos y cualquier otro acto que no haya sido expresamente autorizado por el titular de los derechos de explotaci\u00f3n quedan prohibidos.<\/p>\n\n\n\n<p>El establecimiento de un hiperenlace no implica en ning\u00fan caso la existencia de relaciones entre JESUS PEIRO y el propietario del sitio web en la que se establezca, ni la aceptaci\u00f3n y aprobaci\u00f3n por parte de JESUS PEIRO de sus contenidos o servicios.<\/p>\n\n\n\n<p>JESUS PEIRO no se responsabiliza del uso que cada usuario le d\u00e9 a los materiales puestos a disposici\u00f3n en este sitio web ni de las actuaciones que realice en base a los mismos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. EXCLUSI\u00d3N DE GARANT\u00cdAS Y DE RESPONSABILIDAD<\/h2>\n\n\n\n<p>El contenido del presente sitio web es de car\u00e1cter general y tiene una finalidad meramente informativa, sin que se garantice plenamente el acceso a todos los contenidos, ni su exhaustividad, correcci\u00f3n, vigencia o actualidad, ni su idoneidad o utilidad para un objetivo espec\u00edfico.<\/p>\n\n\n\n<p>JESUS PEIRO excluye, hasta donde permite el ordenamiento jur\u00eddico, cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza derivados de:<\/p>\n\n\n\n<p>a) La imposibilidad de acceso al sitio web o la falta de veracidad, exactitud, exhaustividad y\/o actualidad de los contenidos, as\u00ed como la existencia de vicios y defectos de toda clase de los contenidos transmitidos, difundidos, almacenados, puestos a disposici\u00f3n, a los que se haya accedido a trav\u00e9s del sitio web o de los servicios que se ofrecen.<br>b) La presencia de virus o de otros elementos en los contenidos que puedan producir alteraciones en los sistemas inform\u00e1ticos, documentos electr\u00f3nicos o datos de los usuarios.<br>c) El incumplimiento de las leyes, la buena fe, el orden p\u00fablico, los usos del tr\u00e1fico y el presente aviso legal como consecuencia del uso incorrecto del sitio web. En particular, y a modo ejemplificativo, JESUS PEIRO no se hace responsable de las actuaciones de terceros que vulneren derechos de propiedad intelectual e industrial, secretos empresariales, derechos al honor, a la intimidad personal y familiar y a la propia imagen, as\u00ed como la normativa en materia de competencia desleal y publicidad il\u00edcita.<\/p>\n\n\n\n<p>Asimismo, JESUS PEIRO declina cualquier&nbsp; responsabilidad respecto a la informaci\u00f3n que se halle fuera de esta web y no sea gestionada directamente por nuestro webmaster. La funci\u00f3n de los links que aparecen en esta web es exclusivamente la de informar al usuario sobre la existencia de otras fuentes susceptibles de ampliar los contenidos que ofrece este sitio web. JESUS PEIRO no garantiza ni se responsabiliza del funcionamiento o accesibilidad de los sitios enlazados; ni sugiere, invita o recomienda la visita a los mismos, por lo que tampoco ser\u00e1 responsable del resultado obtenido. JESUS PEIRO no se responsabiliza del establecimiento de hiperv\u00ednculos por parte de terceros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. PROCEDIMIENTO EN CASO DE REALIZACI\u00d3N DE ACTIVIDADES DE<br>CAR\u00c1CTER IL\u00cdCITO<\/h2>\n\n\n\n<p>En el caso de que cualquier usuario o un tercero considere que existen hechos o circunstancias que revelen el car\u00e1cter il\u00edcito de la utilizaci\u00f3n de cualquier contenido y\/o de la realizaci\u00f3n de cualquier actividad en las p\u00e1ginas web incluidas o accesibles a trav\u00e9s del sitio web, deber\u00e1 enviar una notificaci\u00f3n a JESUS PEIRO identific\u00e1ndose debidamente, especificando las supuestas infracciones y declarando expresamente y bajo su responsabilidad que la informaci\u00f3n proporcionada en la notificaci\u00f3n es exacta.<\/p>\n\n\n\n<p>Para toda cuesti\u00f3n litigiosa que incumba al sitio web de JESUS PEIRO, ser\u00e1 de aplicaci\u00f3n la legislaci\u00f3n espa\u00f1ola, siendo competentes los Juzgados y Tribunales de Barcelona (Espa\u00f1a).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5. PUBLICACIONES<\/h2>\n\n\n\n<p>La informaci\u00f3n administrativa facilitada a trav\u00e9s del sitio web no sustituye la publicidad legal de las leyes, normativas, planes, disposiciones generales y actos que tengan que ser publicados formalmente a los diarios oficiales de las administraciones p\u00fablicas, que constituyen el \u00fanico instrumento que da fe de su autenticidad y contenido. La informaci\u00f3n disponible en este sitio web debe entenderse como una gu\u00eda sin prop\u00f3sito de validez legal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"privacidad\">6. POL\u00cdTICA DE PRIVACIDAD<\/h2>\n\n\n\n<p>En INTERSPOSA SA nos preocupamos por la privacidad y la transparencia.<br>A continuaci\u00f3n, le indicamos en detalle los tratamientos de datos personales que realizamos, as\u00ed como toda la informaci\u00f3n relativa a los mismos.<br><strong>\u00bfQui\u00e9n es el responsable del tratamiento de sus datos?<\/strong><br>INTERSPOSA SA<br>A58567439<br>C\/ NOI DEL SUCRE, 61 &#8211; 08840 &#8211; VILADECANS &#8211; BARCELONA<br>936473002<br>admin@jesuspeiro.com<br><strong>\u00bfCu\u00e1les son sus derechos cuando nos facilita sus datos?<\/strong><br>Cualquier persona tiene derecho a obtener confirmaci\u00f3n sobre si en INTERSPOSA SA estamos tratando, o no, datos personales que les conciernan.<br>Las personas interesadas tienen derecho a acceder a sus datos personales, as\u00ed como a solicitar la rectificaci\u00f3n de los datos inexactos o, en su caso, solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sean necesarios para los fines que fueron recogidos.<br>Igualmente tiene derecho a la portabilidad de sus datos.<br>En determinadas circunstancias, los interesados podr\u00e1n solicitar la limitaci\u00f3n del tratamiento de sus datos, en cuyo caso \u00fanicamente los conservaremos para el ejercicio o la defensa de reclamaciones.<br>En determinadas circunstancias y por motivos relacionados con su situaci\u00f3n particular, los interesados podr\u00e1n oponerse al tratamiento de sus datos. En este caso, INTERSPOSA SA dejar\u00e1 de tratar los datos, salvo por motivos leg\u00edtimos imperiosos, o el ejercicio o la defensa de posibles reclamaciones.<br>Podr\u00e1 ejercitar materialmente sus derechos de la siguiente forma: dirigi\u00e9ndose a<br><a href=\"mailto:info@jesusperio.com\">info@jesusperio.com<\/a> o C\/ Noi del Sucre, 61, 08840 Viladecans Barcelona.<\/p>\n\n\n\n<p>Cuando se realice el env\u00edo de comunicaciones comerciales utilizando como base jur\u00eddica<br>el inter\u00e9s leg\u00edtimo del responsable, el interesado podr\u00e1 oponerse al tratamiento de sus<br>datos con ese fin.<br>Si ha otorgado su consentimiento para alguna finalidad concreta, tiene derecho a retirar<br>el consentimiento otorgado en cualquier momento, sin que ello afecte a la licitud del<br>tratamiento basado en el consentimiento previo a su retirada.<br>En caso de que sienta vulnerados sus derechos en lo concerniente a la protecci\u00f3n de sus<br>datos personales, especialmente cuando no haya obtenido satisfacci\u00f3n en el ejercicio de<br>sus derechos, puede presentar una reclamaci\u00f3n ante la Autoridad de Control en materia<br>de Protecci\u00f3n de Datos competente a trav\u00e9s de su sitio web: www.aepd.es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Tratamiento de los datos de los contactos web<\/h3>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 finalidad tratamos sus datos personales?<\/strong><br>En INTERSPOSA SA tratamos la informaci\u00f3n que nos facilitan las personas interesadas con el fin de atender su solicitud y enviarle comunicaciones comerciales y\/o newsletters.<br>En el caso de que no facilite sus datos personales, no podremos cumplir con las finalidades descritas.<br>No se van a tomar decisiones automatizadas en base a los datos proporcionados.<br><strong>\u00bfPor cu\u00e1nto tiempo conservaremos sus datos?<\/strong><br>Los datos se conservar\u00e1n mientras el interesado no solicite su supresi\u00f3n.<br><strong>\u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de sus datos?<\/strong><br>Le indicamos la base legal para el tratamiento de sus datos:<br>\u2022 Ejecuci\u00f3n de un contrato: Atender su solicitud.<br>\u2022 Consentimiento del interesado: Enviar comunicaciones comerciales, inclusive por v\u00eda<br>electr\u00f3nica.<br><strong>\u00bfA qu\u00e9 destinatarios se comunicar\u00e1n sus datos?<\/strong><br>No se ceder\u00e1n datos a terceros, salvo obligaci\u00f3n legal.<\/p>\n\n\n\n<p><strong>Transferencias de datos a terceros pa\u00edses<\/strong><br>Est\u00e1n previstas las siguientes transferencias de datos a terceros pa\u00edses:<br>\u2022 Mailchimp, con la finalidad de Env\u00edo de comunicaciones comerciales yo newsletter..<br>La garant\u00eda para esta transferencia se ha establecido a trav\u00e9s de: Cl\u00e1usulas tipo de<br>protecci\u00f3n de datos. Puede consultar informaci\u00f3n adicional en:<br><a href=\"https:\/\/mailchimp.com\/legal\/privacy\/.\">https:\/\/mailchimp.com\/legal\/privacy\/.<\/a><br><strong>\u00bfC\u00f3mo hemos obtenido sus datos?<\/strong><br>Los datos personales que tratamos en INTERSPOSA SA proceden de: El propio<br>interesado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Tratamiento de los datos del correo electr\u00f3nico<\/h3>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 finalidad tratamos sus datos personales?<\/strong><br>En INTERSPOSA SA tratamos la informaci\u00f3n que nos facilitan las personas interesadas<br>con el fin de prestarle los servicios que nos ha solicitado, atender sus solicitudes de<br>informaci\u00f3n y enviarle comunicaciones comerciales. En el caso de que no facilite sus<br>datos personales, no podremos cumplir con las finalidades descritas.<br>No se van a tomar decisiones automatizadas en base a los datos proporcionados.<br><strong>\u00bfPor cu\u00e1nto tiempo conservaremos sus datos?<\/strong><br>Los datos se conservar\u00e1n mientras el interesado no solicite su supresi\u00f3n.<br><strong>\u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de sus datos?<\/strong><br>Le indicamos la base legal para el tratamiento de sus datos:<br>\u2022 Ejecuci\u00f3n de un contrato: Atender su solicitud.<br>\u2022 Inter\u00e9s leg\u00edtimo del Responsable: Contacto y env\u00edo de comunicaciones comerciales<br>sobre nuestros servicios y productos en base al inter\u00e9s demostrado acerca de nuestros<br>productos y servicios.<br>\u2022 Consentimiento del interesado: Env\u00edo de comunicaciones comerciales sobre nuestros<br>servicios y\/o productos.<\/p>\n\n\n\n<p><strong>\u00bfA qu\u00e9 destinatarios se comunicar\u00e1n sus datos?<\/strong><br>No se ceder\u00e1n datos a terceros, salvo obligaci\u00f3n legal.<br><strong>Transferencias de datos a terceros pa\u00edses<\/strong><br>No est\u00e1n previstas transferencias de datos a terceros pa\u00edses.<br><strong>\u00bfC\u00f3mo hemos obtenido sus datos?<\/strong><br>Los datos personales que tratamos en INTERSPOSA SA proceden de: El propio<br>interesado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Tratamiento de los datos de candidatos a un puesto de trabajo<\/h3>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 finalidad tratamos sus datos personales?<\/strong><br>En INTERSPOSA SA tratamos la informaci\u00f3n que nos facilitan las personas interesadas<br>con el fin de gestionar los Curriculum Vitae recibidos y realizar los procesos de selecci\u00f3n<br>de personal, entrevistas y dem\u00e1s tr\u00e1mites necesarios para la b\u00fasqueda del mejor candidato<br>posible a un puesto de trabajo determinado. En el caso de que no facilite sus datos<br>personales, no podremos cumplir con las finalidades descritas.<br>No se van a tomar decisiones automatizadas en base a los datos proporcionados.<br><strong>\u00bfPor cu\u00e1nto tiempo conservaremos sus datos?<\/strong><br>Dos a\u00f1os desde la \u00faltima interacci\u00f3n.<br><strong>\u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de sus datos?<\/strong><br>Le indicamos la base legal para el tratamiento de sus datos:<br>\u2022 Ejecuci\u00f3n de un contrato: Gest\u00edon de los Curriculum Vitae entregados por el<br>candidato para realizar los procesos de selecci\u00f3n de personal para la b\u00fasqueda del<br>mejor candidato posible a un puesto de trabajo determinado.<br><strong>\u00bfA qu\u00e9 destinatarios se comunicar\u00e1n sus datos?<\/strong><br>No se ceder\u00e1n datos a terceros, salvo obligaci\u00f3n legal.<\/p>\n\n\n\n<p><strong>Transferencias de datos a terceros pa\u00edses<br><\/strong>No est\u00e1n previstas transferencias de datos a terceros pa\u00edses.<br><strong>\u00bfC\u00f3mo hemos obtenido sus datos?<\/strong><br>Los datos personales que tratamos en INTERSPOSA SA proceden de: El propio<br>interesado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Tratamiento de los datos de clientes \u2013 contratos &#8211; presupuestos<\/h3>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 finalidad tratamos sus datos personales?<\/strong><br>En INTERSPOSA SA tratamos la informaci\u00f3n que nos facilitan las personas interesadas<br>con el fin de realizar la gesti\u00f3n administrativa, contable y fiscal de los servicios<br>solicitados, as\u00ed como enviar comunicaciones comerciales y\/o newsletters sobre nuestros<br>productos y servicios. En el caso de que no facilite sus datos personales, no podremos<br>cumplir con las finalidades descritas.<br>No se van a tomar decisiones automatizadas en base a los datos proporcionados.<br><strong>\u00bfPor cu\u00e1nto tiempo conservaremos sus datos?<\/strong><br>Los datos se conservar\u00e1n mientras el interesado no solicite su supresi\u00f3n, y en su caso,<br>durante los a\u00f1os necesarios para cumplir con las obligaciones legales.<br><strong>\u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de sus datos?<\/strong><br>Le indicamos la base legal para el tratamiento de sus datos:<br>\u2022 Ejecuci\u00f3n de un contrato: Realizar la gesti\u00f3n administrativa, contable y fiscal de los<br>servicios solicitados.<br>\u2022 Consentimiento del interesado: Env\u00edo de comunicaciones comerciales incluso por v\u00eda<br>electr\u00f3nica.<br><strong>\u00bfA qu\u00e9 destinatarios se comunicar\u00e1n sus datos?<\/strong><br>Los datos se comunicar\u00e1n a los siguientes destinatarios:<br>\u2022 Administraci\u00f3n Tributaria, con la finalidad de cumplir con las obligaciones legales<br>(requisito legal).<\/p>\n\n\n\n<p>\u2022 En su caso, empresa mensajer\u00eda o transporte, con la finalidad de gesti\u00f3n de la<br>recogida, seguimiento y entrega de los env\u00edos (requisito contractual).<br>\u2022 Entidades financieras, con la finalidad de girar los recibos correspondientes (requisito<br>contractual).<br><strong>Transferencias de datos a terceros pa\u00edses<\/strong><br>Est\u00e1n previstas las siguientes transferencias de datos a terceros pa\u00edses:<br>\u2022 Mailchimp, con la finalidad de Env\u00edo de comunicaciones comerciales y\/o newsletter..<br>La garant\u00eda para esta transferencia se ha establecido a trav\u00e9s de: Cl\u00e1usulas tipo de<br>protecci\u00f3n de datos. Puede consultar informaci\u00f3n adicional en:<br>https:\/\/mailchimp.com\/legal\/privacy\/.<br><strong>\u00bfC\u00f3mo hemos obtenido sus datos?<\/strong><br>Los datos personales que tratamos en INTERSPOSA SA proceden de: El propio<br>interesado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Tratamiento de los datos de candidatos a un puesto de trabajo<\/h3>\n\n\n\n<p><strong>\u00bfCon qu\u00e9 finalidad tratamos sus datos personales?<\/strong><br>En INTERSPOSA SA tratamos la informaci\u00f3n que nos facilitan las personas interesadas<br>con el fin de gestionar los Curriculum Vitae recibidos y realizar los procesos de selecci\u00f3n<br>de personal, entrevistas y dem\u00e1s tr\u00e1mites necesarios para la b\u00fasqueda del mejor candidato<br>posible a un puesto de trabajo determinado. En el caso de que no facilite sus datos<br>personales, no podremos cumplir con las finalidades descritas.<br>No se van a tomar decisiones automatizadas en base a los datos proporcionados.<br><strong>\u00bfPor cu\u00e1nto tiempo conservaremos sus datos?<\/strong><br>Dos a\u00f1os desde la \u00faltima interacci\u00f3n.<br><strong>\u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de sus datos?<\/strong><br>Le indicamos la base legal para el tratamiento de sus datos:<\/p>\n\n\n\n<p>\u2022 Ejecuci\u00f3n de un contrato: Gesti\u00f3n de los Curr\u00edculum Vitae entregados por el<br>candidato para realizar los procesos de selecci\u00f3n de personal para la b\u00fasqueda del<br>mejor candidato posible a un puesto de trabajo determinado.<br><strong>\u00bfA qu\u00e9 destinatarios se comunicar\u00e1n sus datos?<\/strong><br>No se ceder\u00e1n datos a terceros, salvo obligaci\u00f3n legal.<br><strong>Transferencias de datos a terceros pa\u00edses<\/strong><br>No est\u00e1n previstas transferencias de datos a terceros pa\u00edses.<br><strong>\u00bfC\u00f3mo hemos obtenido sus datos?<\/strong><br>Los datos personales que tratamos en INTERSPOSA SA proceden de: El propio<br>interesado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"politica-de-cookies\">7. POLITICA DE COOKIES<\/h2>\n\n\n\n<p><strong>\u00bfQu\u00e9 son las cookies?<\/strong><\/p>\n\n\n\n<p>Una cookie es un fichero que se descarga descarga en su ordenador al acceder a determinadas p\u00e1ginas web. Las cookies permiten a una p\u00e1gina web, entre otras cosas, almacenar y recuperar informaci\u00f3n sobre los h\u00e1bitos de navegaci\u00f3n de un usuario o de su equipo y, dependiendo de la informaci\u00f3n que contengan y de la forma en que utilice su equipo, pueden utilizarse para reconocer al usuario.<\/p>\n\n\n\n<p><strong>\u00bfPara qu\u00e9 utiliza las cookies esta p\u00e1gina web y cu\u00e1les son?<\/strong><\/p>\n\n\n\n<p>Esta p\u00e1gina web utiliza las cookies para una serie de finalidades, incluidas:<\/p>\n\n\n\n<p><strong>An\u00e1lisis estad\u00edstico<\/strong><\/p>\n\n\n\n<p>Las cookies estad\u00edsticas ayudan a los propietarios de p\u00e1ginas web a comprender c\u00f3mo interact\u00faan los visitantes con las p\u00e1ginas web reuniendo y proporcionando informaci\u00f3n como cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n<br>que hacen los usuarios del servicio<\/p>\n\n\n\n<p>El detalle de las cookies de an\u00e1lisis utilizadas en esta p\u00e1gina web es el siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Cookies<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Nombre<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Tipo<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Prop\u00f3sito<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>M\u00e1s informaci\u00f3n<\/u><\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_ga <\/span><span style=\"font-family: Arial, serif;\">_gat<\/span><span style=\"font-family: Arial, serif;\"> _gid _<\/span><span style=\"font-family: Arial, serif;\">gat_UA-1061048-13<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Google Analytics<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">De terceros<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Recoger informaci\u00f3n sobre la navegaci\u00f3n de los usuarios por el sitio con el fin de conocer el origen de las visitas y otros datos similares a nivel estad\u00edstico. No obtiene datos de los nombres o apellidos de los usuarios ni de la direcci\u00f3n postal concreta desde donde se conectan.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Centro de privacidad de Google: http:\/\/www.google.com\/intl\/es\/policies\/privacy\/<\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_YSC _GPS<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">An\u00e1lisis Youtube<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">De terceros<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Miden las reproducciones de videos realizadas por el usuario y registra los eventos de &#8222;Me gusta&#8220; o &#8222;Compartir video&#8220;. Tambi\u00e9n registra una identificaci\u00f3n \u00fanica en dispositivos m\u00f3viles para permitir el seguimiento seg\u00fan la ubicaci\u00f3n geogr\u00e1fica por GPS y los v\u00eddeos m\u00e1s recientes que se han visto en un navegador espec\u00edfico.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Centro de privacidad de Google: https:\/\/policies.google.com\/technologies\/cookies?hl=es<\/span><\/p>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>T\u00e9cnicas o necesarias<\/strong><\/p>\n\n\n\n<p>Son aquellas que se utilizan para la navegaci\u00f3n y el buen funcionamiento de nuestra p\u00e1gina web. Permiten por ejemplo, controlar el tr\u00e1fico y la comunicaci\u00f3n de datos, acceder a partes de acceso restringido, utilizar elementos de seguridad, almacenar contenidos para poder difundir v\u00eddeos o compartir contenidos a trav\u00e9s de redes sociales.<\/p>\n\n\n\n<p>El detalle de las cookies t\u00e9cnicas o necesarias utilizadas en esta p\u00e1gina web es el siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Cookies<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Nombre<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Tipo<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Prop\u00f3sito<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>M\u00e1s informaci\u00f3n<\/u><\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">cdp-cookies-plugin-wp<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">T\u00e9cnica jesuspeiro.com<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">Propia<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Cookie para saber si el usuario ha aceptado la pol\u00edtica de cookies.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">En la propia p\u00e1gina web.<\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_jpfavoritos<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">T\u00e9cnica jesuspeiro.com<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">Propia<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Identificaci\u00f3n de vestidos marcados como favoritos.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">En la propia p\u00e1gina web.<\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_wordpress_b _wordpress_logged_in _wordpress_test_cookies<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">T\u00e9cnica WordPress<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">De terceros<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Cookies para usuarios registrados o administradores.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Centro de privacidad WordPress: https:\/\/en.support.wordpress.com\/cookies\/<\/span><\/p>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Publicitaria<\/strong><\/p>\n\n\n\n<p>Son aqu\u00e9llas que permiten la gesti\u00f3n, de la forma m\u00e1s eficaz posible, de los espacios publicitarios que, en su caso, el editor haya incluido en una p\u00e1gina web, aplicaci\u00f3n o plataforma desde la que presta el servicio solicitado en base a criterios como el contenido editado o la frecuencia en la que se muestran los anuncios.<\/p>\n\n\n\n<p>El detalle de las cookies publicitarias utilizadas en esta p\u00e1gina web es el siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Cookies<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Nombre<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Tipo<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Prop\u00f3sito<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>M\u00e1s informaci\u00f3n<\/u><\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_fbp<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Publicit\u00e1ria Facebook<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">De terceros<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Utilizado por facebook para repartir una serie de anuncios de productos como las apuestas en tiempo real de terceros.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Centro de privacidad de Facebook: https:\/\/www.facebook.com\/policies\/cookies\/<\/span><\/p>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Personalizaci\u00f3n o preferencia<\/strong><\/p>\n\n\n\n<p>Son aqu\u00e9llas que permiten al usuario acceder al servicio con algunas caracter\u00edsticas de car\u00e1cter general predefinidas en funci\u00f3n de una serie de criterios en el terminal del usuario como por ejemplo ser\u00edan el aspecto que tiene, como su idioma preferido o la regi\u00f3n en la que usted se encuentra.<\/p>\n\n\n\n<p>El detalle de las cookies de personalizaci\u00f3n o preferencia utilizadas en esta p\u00e1gina web es el siguiente:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Cookies<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Nombre<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Tipo<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>Prop\u00f3sito<\/u><\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\"><u>M\u00e1s informaci\u00f3n<\/u><\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_PREF _VISITOR_INFO1_LIVE<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Preferencia YouTube<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">De terceros<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Cookies que almacenan las preferencias de configuraci\u00f3n, tales como idioma preferido, n\u00famero de resultados de b\u00fasqueda mostrados por p\u00e1gina o activaci\u00f3n del filtro SafeSearch de Google.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Centro de privacidad de Google: https:\/\/policies.google.com\/technologies\/cookies?hl=es<\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_icl_current_language _icl_admin_language<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Preferencia jesuspeiro.com<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">Propia<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Gesti\u00f3n de los idiomas utilizados en la web.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">En la propia p\u00e1gina web.<\/span><\/p>\n<\/td><\/tr><tr><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">_wp-settings-1 _Wp-settings-time-1<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Preferencia WordPress<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\" align=\"CENTER\"><span style=\"font-family: Arial, serif;\">De terceros<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Son utilizadas para personalizar la interfaz de usuario.<\/span><\/p>\n<\/td><td>\n<p lang=\"es-ES\"><span style=\"font-family: Arial, serif;\">Centro de privacidad WordPress: https:\/\/en.support.wordpress.com\/cookies\/<\/span><\/p>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Nota: Las cookies de tipo &#8218;Propias&#8216; son utilizadas s\u00f3lo por el propietario de esta web y las cookies &#8218;De terceros&#8216; son utilizadas, por el prestador del servicio que est\u00e1 detallado en el cuadro anterior.<\/p>\n\n\n\n<p><strong>Eliminar o bloquear las cookies<\/strong><\/p>\n\n\n\n<p>Usted puede permitir, bloquear o eliminar las cookies instaladas en su equipo mediante la configuraci\u00f3n de las opciones del navegador instalado en su ordenador.<\/p>\n\n\n\n<p>Pueder ver m\u00e1s informaci\u00f3n sobre su navegador y las cookies en los siguientes enlaces:<\/p>\n\n\n\n<p>o Firefox: http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-lossitios- we<\/p>\n\n\n\n<p>o Chrome: http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647<\/p>\n\n\n\n<p>o Internet Explorer: http:\/\/windows.microsoft.com\/es-es\/windows7\/how-to-managecookies- in-internet-explorer-9<\/p>\n\n\n\n<p>o Safari: http:\/\/support.apple.com\/kb\/ph5042<\/p>\n\n\n\n<p>o Opera: http:\/\/help.opera.com\/Windows\/11.50\/es-ES\/cookies.html<\/p>\n\n\n\n<p><strong>Complemento de inhabilitaci\u00f3n para navegadores de Google Analytics <\/strong><\/p>\n\n\n\n<p>Si desea rechazar las cookies anal\u00edticas de Google Analytics en todos los navegadores, de forma que no se env\u00ede informaci\u00f3n suya a Google Analitys, puede descargar un complemento que realiza esta funci\u00f3n desde este enlace: https:\/\/tools.google.com\/dlpage\/gaoptout.<\/p>\n\n\n\n<p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>0. OBJETO Y ACEPTACI\u00d3N El presente aviso legal regula el uso y utilizaci\u00f3n del sitio web www.jesuspeiro.com (en adelante, LA WEB), del que es titular INTERSPOSA SA (en adelante, JESUS PEIRO). La navegaci\u00f3n por el sitio web de JESUS PEIRO le atribuye la condici\u00f3n de usuario del mismo y conlleva su aceptaci\u00f3n plena y sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-30682","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"pjPfsMP1_H2i6kYQK3aGHDuXtt6pTjE7BWHII5RZOKo\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/#listItem\",\"name\":\"Aviso legal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/#listItem\",\"position\":2,\"name\":\"Aviso legal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/#organization\",\"name\":\"JESUS PEIRO\",\"description\":\"Vestidos de novia hechos en Espa\\u00f1a\",\"url\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/\",\"telephone\":\"+34936473002\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.jesuspeiro.com\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logo.png\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/#organizationLogo\",\"width\":300,\"height\":300,\"caption\":\"Logo JESUS PEIRO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/jesuspeiroofficial\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@jesuspeiroofficial\",\"https:\\\/\\\/es.pinterest.com\\\/jesuspeiro\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jesus-peiro\\\/?originalSubdomain=es\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/#webpage\",\"url\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/\",\"name\":\"Aviso legal | JESUS PEIRO\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/nota-legal\\\/#breadcrumblist\"},\"datePublished\":\"2015-12-09T17:07:50+00:00\",\"dateModified\":\"2025-04-18T14:14:11+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/\",\"name\":\"JESUS PEIRO\",\"description\":\"Vestidos de novia hechos en Espa\\u00f1a\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jesuspeiro.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Aviso legal | JESUS PEIRO","description":"","canonical_url":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"pjPfsMP1_H2i6kYQK3aGHDuXtt6pTjE7BWHII5RZOKo","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.jesuspeiro.com\/de\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.jesuspeiro.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/#listItem","name":"Aviso legal"}},{"@type":"ListItem","@id":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/#listItem","position":2,"name":"Aviso legal","previousItem":{"@type":"ListItem","@id":"https:\/\/www.jesuspeiro.com\/de\/#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/www.jesuspeiro.com\/de\/#organization","name":"JESUS PEIRO","description":"Vestidos de novia hechos en Espa\u00f1a","url":"https:\/\/www.jesuspeiro.com\/de\/","telephone":"+34936473002","logo":{"@type":"ImageObject","url":"https:\/\/www.jesuspeiro.com\/wp-content\/uploads\/2015\/12\/logo.png","@id":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/#organizationLogo","width":300,"height":300,"caption":"Logo JESUS PEIRO"},"image":{"@id":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/jesuspeiroofficial\/","https:\/\/www.tiktok.com\/@jesuspeiroofficial","https:\/\/es.pinterest.com\/jesuspeiro\/","https:\/\/www.linkedin.com\/company\/jesus-peiro\/?originalSubdomain=es"]},{"@type":"WebPage","@id":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/#webpage","url":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/","name":"Aviso legal | JESUS PEIRO","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.jesuspeiro.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/#breadcrumblist"},"datePublished":"2015-12-09T17:07:50+00:00","dateModified":"2025-04-18T14:14:11+00:00"},{"@type":"WebSite","@id":"https:\/\/www.jesuspeiro.com\/de\/#website","url":"https:\/\/www.jesuspeiro.com\/de\/","name":"JESUS PEIRO","description":"Vestidos de novia hechos en Espa\u00f1a","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.jesuspeiro.com\/de\/#organization"}}]}},"aioseo_meta_data":{"post_id":"30682","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-01 14:37:33","updated":"2025-06-19 10:16:32","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.jesuspeiro.com\/de\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAviso legal\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.jesuspeiro.com\/de\/"},{"label":"Aviso legal","link":"https:\/\/www.jesuspeiro.com\/de\/nota-legal\/"}],"_links":{"self":[{"href":"https:\/\/www.jesuspeiro.com\/de\/wp-json\/wp\/v2\/pages\/30682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jesuspeiro.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jesuspeiro.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jesuspeiro.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jesuspeiro.com\/de\/wp-json\/wp\/v2\/comments?post=30682"}],"version-history":[{"count":0,"href":"https:\/\/www.jesuspeiro.com\/de\/wp-json\/wp\/v2\/pages\/30682\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.jesuspeiro.com\/de\/wp-json\/wp\/v2\/media?parent=30682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}